{"id":9914,"date":"2020-05-07T01:56:59","date_gmt":"2020-05-06T22:56:59","guid":{"rendered":"https:\/\/www.oitchau.com.br\/blog\/?p=9914"},"modified":"2023-11-29T17:02:11","modified_gmt":"2023-11-29T14:02:11","slug":"como-praticar-e-aplicar-a-diversidade-dentro-da-empresa","status":"publish","type":"post","link":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/","title":{"rendered":"Diversidade dentro da empresa: como praticar e aplicar?"},"content":{"rendered":"\r\n<p>Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es que querem se manter relevantes e chamativas aos olhos do p\u00fablico.<\/p>\r\n\r\n\r\n\r\n<p>Mas o que exatamente \u00e9 diversidade? Por que ela \u00e9 importante para as empresas e como foment\u00e1-la? N\u00e3o se preocupe, preparamos um conte\u00fado especial!<\/p>\r\n\r\n\r\n\r\n<p>Veja abaixo como pratic\u00e1-la e aplic\u00e1-la e, de quebra, garantir melhores resultados.<\/p>\r\n\r\n\r\n\r\n<ul>\r\n<li><strong><a href=\"#ancora01\" data-type=\"internal\" data-id=\"#ancora01\">Diversidade nas empresas: o que significa?<\/a><\/strong><\/li>\r\n<li><strong><a href=\"#ancora02\" data-type=\"internal\" data-id=\"#ancora02\">Qual a import\u00e2ncia da diversidade no ambiente corporativo?<\/a><\/strong><\/li>\r\n<li><strong><a href=\"#ancora03\" data-type=\"internal\" data-id=\"#ancora03\">Quais as vantagens da pluralidade dentro de uma empresa?<\/a><\/strong>\r\n<ul>\r\n<li><a href=\"#ancora04\" data-type=\"internal\" data-id=\"#ancora04\"><strong>Aumento da criatividade do grupo<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora05\" data-type=\"internal\" data-id=\"#ancora05\"><strong>Proposi\u00e7\u00e3o de solu\u00e7\u00f5es diversas para um problema<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora06\" data-type=\"internal\" data-id=\"#ancora06\"><strong>Abertura de oportunidades para a inova\u00e7\u00e3o e aumento da conex\u00e3o com um p\u00fablico maior<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora07\" data-type=\"internal\" data-id=\"#ancora07\"><strong>Constru\u00e7\u00e3o de imagem perante o p\u00fablico<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora08\" data-type=\"internal\" data-id=\"#ancora08\"><strong>Desenvolvimento de um clima organizacional mais prop\u00edcio ao crescimento pessoal e profissional dos funcion\u00e1rios<\/strong><\/a><\/li>\r\n<\/ul>\r\n<\/li>\r\n<li><a href=\"#ancora09\" data-type=\"internal\" data-id=\"#ancora09\"><strong>Como promover e aplicar a diversidade dentro das empresas?<\/strong><\/a>\r\n<ul>\r\n<li><a href=\"#ancora10\" data-type=\"internal\" data-id=\"#ancora10\"><strong>Avalie e mensure o quadro de funcion\u00e1rios<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora11\" data-type=\"internal\" data-id=\"#ancora11\"><strong>Trabalhe a cultura organizacional<\/strong><\/a><\/li>\r\n<li><a href=\"#ancora12\" data-type=\"internal\" data-id=\"#ancora12\"><strong>Preste aten\u00e7\u00e3o aos processos de recrutamento<\/strong><\/a><\/li>\r\n<li><strong><a href=\"#ancora13\" data-type=\"internal\" data-id=\"#ancora13\">Invista na comunica\u00e7\u00e3o interna<\/a><\/strong><\/li>\r\n<\/ul>\r\n<\/li>\r\n<\/ul>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"ancora01\">Diversidade nas empresas: o que significa?<\/h2>\r\n\r\n\r\n\r\n<p>A diversidade se ilustra por meio da pluralidade, dentro de uma empresa, relacionada ao g\u00eanero, ra\u00e7a, idade e sexualidade de seus colaboradores. Ou seja, nesse caso h\u00e1 uma fuga do padr\u00e3o e a valoriza\u00e7\u00e3o da pluralidade.<\/p>\r\n\r\n\r\n\r\n<p>Assim, pode ser considerada como uma equipe diversa aquela que possui em sua composi\u00e7\u00e3o pessoas de diferentes forma\u00e7\u00f5es, g\u00eaneros, ra\u00e7as, experi\u00eancias e posicionamentos.<\/p>\r\n\r\n\r\n\r\n<p>As novas gera\u00e7\u00f5es est\u00e3o dentre as grandes respons\u00e1veis por essa mudan\u00e7a de foco e valoriza\u00e7\u00e3o da pluralidade, uma vez que fomentam discuss\u00f5es do tipo.<\/p>\r\n\r\n\r\n\r\n<p>As mudan\u00e7as trazidas por elas geram claro reflexo no mercado de trabalho, uma vez que s\u00e3o esses indiv\u00edduos que compor\u00e3o a for\u00e7a de trabalho, a m\u00e3o-de-obra das empresas que comp\u00f5em o mercado.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>Portanto, temas como acessibilidade, empoderamento e diversidade ganharam for\u00e7a na pauta empresarial, bem como na sociedade, invadindo desde conversas de botequim a discuss\u00f5es conjuntas em grandes empresas.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"ancora02\">Qual a import\u00e2ncia da diversidade no ambiente corporativo?<\/h2>\r\n\r\n\r\n\r\n<p>Essas novas discuss\u00f5es afastaram a padroniza\u00e7\u00e3o dos colaboradores de uma empresa para a abertura das portas \u00e0 pluralidade e \u00e0 multiculturalidade que trazem diversos benef\u00edcios \u00e0 pr\u00f3pria organiza\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p>A diversidade n\u00e3o s\u00f3 permite que a empresa tenha diversas culturas em um mesmo ambiente, mas possibilita que essa pluralidade encontre novas solu\u00e7\u00f5es e novos formatos de atua\u00e7\u00e3o.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>Tornando uma empresa muito mais competitiva, ganhando uma notoriedade muito maior, j\u00e1 que existe um p\u00fablico que est\u00e1 atento \u00e0 essas quest\u00f5es, e se preocupe com os produtos que consume, e com as empresas que comercializam.<\/p>\r\n\r\n\r\n\r\n<p>Embora aplicar e praticar a diversidade dentro da sua empresa possa parecer um desafio, h\u00e1 algumas dicas importantes para tornar sua empresa mais plural!<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"ancora03\">Quais as vantagens da pluralidade dentro de uma empresa?<\/h2>\r\n\r\n\r\n\r\n<p>\u00c9 necess\u00e1rio destacar, com maiores detalhes, a import\u00e2ncia da diversidade dentro de uma empresa. S\u00e3o diversos os motivos que as tornam especiais perante as organiza\u00e7\u00f5es, veja alguns.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora04\"><strong>Aumento da criatividade do grupo<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>Quando se tem uma equipe formada prioritariamente por membros com as mesmas caracter\u00edsticas, experi\u00eancias e vis\u00f5es de mundo a criatividade tende a ser limitada.<\/p>\r\n\r\n\r\n\r\n<p>Investir na pluralidade dos membros possibilita que cada um deles, com base em suas vis\u00f5es diferenciadas, exercitem a criatividade do grupo.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora05\"><strong>Proposi\u00e7\u00e3o de solu\u00e7\u00f5es diversas para um problema<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>Essa vantagem est\u00e1 intimamente ligada \u00e0 anterior. Isso porque o maior uso da criatividade tamb\u00e9m possibilita que in\u00fameras proposi\u00e7\u00f5es, de natureza diversa, sejam propostas.<\/p>\r\n\r\n\r\n\r\n<p>Ou seja, uma equipe homog\u00eanea tende a focar em uma solu\u00e7\u00e3o, enquanto a heterog\u00eanea possibilita a apresenta\u00e7\u00e3o de mais de uma solu\u00e7\u00e3o utilizando caminhos diversos.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora06\"><strong>Abertura de oportunidades para a inova\u00e7\u00e3o e aumento da conex\u00e3o com um p\u00fablico maior<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>A diversidade interna reflete externamente, tamb\u00e9m. Ou seja, a pluralidade dentre os colaboradores de sua empresa que atuam de formas diversas e prop\u00f5em diferentes solu\u00e7\u00f5es tamb\u00e9m atrai outros p\u00fablicos.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora07\"><strong>Constru\u00e7\u00e3o de imagem perante o p\u00fablico<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>A pluralidade \u00e9 importante na medida em que demonstra ao p\u00fablico a preocupa\u00e7\u00e3o da empresa com a diversidade, fazendo com que ele se sinta representado, portanto.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora08\"><strong>Desenvolvimento de um clima organizacional mais prop\u00edcio ao crescimento pessoal e profissional dos funcion\u00e1rios<\/strong><\/h3>\r\n\r\n\r\n\r\n<p>A constru\u00e7\u00e3o de equipes heterog\u00eaneas permite que uns aprendam com os outros com base em suas diferentes percep\u00e7\u00f5es, de forma que todos saem ganhando.<\/p>\r\n\r\n\r\n\r\n<p>Todas essas vantagens da diversidade dentro das empresas somente se configuram quando essa pluralidade \u00e9 entendida como realmente necess\u00e1ria.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\" id=\"ancora09\">Como promover e aplicar a diversidade dentro das empresas?<\/h2>\r\n\r\n\r\n\r\n<p>Existem diversas formas de impulsionar o desenvolvimento e enraizamento da diversidade nas empresas. Abaixo, separamos um passo a passo que pode auxiliar em muito nessa empreitada.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora10\">Avalie e mensure o quadro de funcion\u00e1rios<\/h3>\r\n\r\n\r\n\r\n<p>Primeiramente, \u00e9 necess\u00e1rio promover uma avalia\u00e7\u00e3o profunda do quadro de funcion\u00e1rios. Dessa maneira, deve-se estudar cada uma das equipes que comp\u00f5e a organiza\u00e7\u00e3o com base na <a href=\"https:\/\/www.oitchau.com.br\/blog\/inclusao-de-pessoas-transgenero-no-mercado-de-trabalho\/\">diversidade de g\u00eaneros<\/a>, ra\u00e7a, sexualidade, idade e outros.<\/p>\r\n\r\n\r\n\r\n<p>Al\u00e9m disso, procure analisar o que levou \u00e0 contrata\u00e7\u00e3o dessas pessoas em espec\u00edfico. Ap\u00f3s, analise novamente sua empresa com base no quadro geral, quando \u00e9 poss\u00edvel entender quais equipes s\u00e3o mais ou menos destoantes quanto \u00e0 pluralidade.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora11\">Trabalhe a cultura organizacional<\/h3>\r\n\r\n\r\n\r\n<p>Procure entender se h\u00e1 algum tipo de sentimento, por certos membros ou equipes, de exclus\u00e3o, ou ainda se essa cultura de alguma forma se manifesta no interior da institui\u00e7\u00e3o empresarial.<\/p>\r\n\r\n\r\n\r\n<p>Tamb\u00e9m, procure levantar questionamentos sobre a possibilidade de a empresa valorizar sempre o mesmo tipo de profissional ou caracter\u00edstica pessoal, assim como se existe, internamente, espa\u00e7o dedicado \u00e0 inova\u00e7\u00e3o e \u00e0 valoriza\u00e7\u00e3o da inclus\u00e3o.<\/p>\r\n\r\n\r\n\r\n<p>Nesse sentido, ideias divergentes ou fora dos padr\u00f5es comuns s\u00e3o acatadas ou ao menos analisadas e estudadas com aten\u00e7\u00e3o? H\u00e1 espa\u00e7o para manifesta\u00e7\u00e3o dos empregados? H\u00e1 clareza quanto \u00e0 liberdade interna e \u00e0 fomenta\u00e7\u00e3o da criatividade?<\/p>\r\n\r\n\r\n\r\n<p>Essas s\u00e3o apenas algumas das perguntas que os gestores devem fazer a si mesmos quando o assunto \u00e9 diversidade dentro da empresa.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora12\">Preste aten\u00e7\u00e3o aos processos de recrutamento<\/h3>\r\n\r\n\r\n\r\n<p>Para tornar uma empresa diversificada em rela\u00e7\u00e3o aos seus colaboradores \u00e9 necess\u00e1rio tamb\u00e9m uma an\u00e1lise sobre os <a href=\"https:\/\/www.oitchau.com.br\/blog\/recrutamento-e-selecao-de-pessoas-guia-completo\/\">processos de recrutamento<\/a> que s\u00e3o utilizados.<\/p>\r\n\r\n\r\n\r\n<p>Nesse sentido, \u00e9 necess\u00e1rio se livrar de processos que sempre focam nas mesmas caracter\u00edsticas pessoais, forma\u00e7\u00e3o universit\u00e1ria (tanto quanto \u00e0 institui\u00e7\u00e3o quando ao curso) e outros.<\/p>\r\n\r\n\r\n\r\n<p>Isso porque esse tipo de processo tende a pender para a heterogeneidade das equipes, que \u00e9 o que justamente est\u00e1 se buscando mudar.<\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>Dessa maneira, evite fazer processos seletivos que, de alguma maneira, permitam que preconceitos at\u00e9 mesmo inconscientes se manifestem.<\/p>\r\n\r\n\r\n\r\n<p>Uma boa forma de evitar esse tipo de sele\u00e7\u00e3o que, mesmo de forma inconsciente, exclui parte de seus bons candidatos por fatores aleat\u00f3rios, \u00e9 investir no uso de softwares e ferramentas de recrutamento.<\/p>\r\n\r\n\r\n\r\n<p>Essas t\u00eam o poder de identificar quem s\u00e3o as pessoas que se candidataram \u00e0(s) vaga(s) e que realmente s\u00e3o qualificadas para a vaga.<\/p>\r\n\r\n\r\n\r\n<p>Nesse sentido \u00e9 poss\u00edvel driblar fatores que podem ser motivos de discrimina\u00e7\u00e3o mesmo que este seja, repita-se inconsciente. Contrata\u00e7\u00f5es \u00e0s cegas tamb\u00e9m s\u00e3o \u00f3timas op\u00e7\u00f5es para aumentar a diversidade dentro da equipe.<\/p>\r\n\r\n\r\n\r\n<h3 class=\"wp-block-heading\" id=\"ancora13\">Invista na comunica\u00e7\u00e3o interna<\/h3>\r\n\r\n\r\n\r\n<p>A <a href=\"https:\/\/www.oitchau.com.br\/blog\/comunicacao-interna-erros-que-prejudicam-a-empresa\/\">comunica\u00e7\u00e3o interna<\/a> est\u00e1 intimamente ligada \u00e0 promo\u00e7\u00e3o da diversidade interna de uma empresa, pois \u00e9 por meio dela que ser\u00e1 poss\u00edvel demonstrar \u00e0 valoriza\u00e7\u00e3o das diferen\u00e7as, assim como fomentar um ambiente democr\u00e1tico e de trocas de ideias que, por sua vez, tendem a auxiliar a empresa e a aumentar a criatividade de suas equipes.<\/p>\r\n\r\n\r\n\r\n<p>\u00c9 necess\u00e1rio trabalhar o acolhimento entre os colaboradores, assim como, se necess\u00e1rio, fomentar palestras e discuss\u00f5es que digam respeito \u00e0s diferen\u00e7as e \u00e0 valoriza\u00e7\u00e3o de todos os colaboradores em suas pr\u00f3prias pluralidades.<\/p>\r\n\r\n\r\n\r\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Ressalta-se que al\u00e9m de atrair colaboradores mais diversos para a empresa \u00e9 necess\u00e1rio que esta instru\u00e7\u00e3o saiba como manter essa diversidade. <\/span><\/span><\/p>\r\n\r\n\r\n\r\n<p><span style=\"vertical-align: inherit;\"><span style=\"vertical-align: inherit;\">Dessa forma, portanto, \u00e9 preciso que sejam criados mecanismos que possam facilitar a intera\u00e7\u00e3o e a constru\u00e7\u00e3o de rela\u00e7\u00f5es saud\u00e1veis \u200b\u200be uma comunica\u00e7\u00e3o fluida entre desiguais.<\/span><\/span><\/p>\r\n\r\n\r\n\r\n<p>Assim, busque formas para fazer com que a intera\u00e7\u00e3o entre as equipes heterogeneamente formadas seja maior, assim como para faz\u00ea-las valorizar o trabalho e desenvolvimento de ideias de quem age e pensa de maneira diversa.<\/p>\r\n\r\n\r\n\r\n<p>A diversidade somente tende a acrescer \u00e0s empresas, uma vez que ela possibilita que haja o desenvolvimento de t\u00e9cnicas e solu\u00e7\u00f5es diferenciadas, bem como fa\u00e7a com que a institui\u00e7\u00e3o cres\u00e7a aos olhos n\u00e3o s\u00f3 do p\u00fablico, mas do pr\u00f3prio mercado de trabalho e dos melhores profissionais que buscam se colocar nas melhores empresas.<\/p>\r\n\r\n\r\n\r\n<p>Colocar em pr\u00e1tica os questionamentos acima listados, portanto, \u00e9 essencial para que se d\u00ea in\u00edcio a uma era plural dentro da empresa por meio n\u00e3o s\u00f3 da autoan\u00e1lise comportamental da institui\u00e7\u00e3o, mas tamb\u00e9m com a proposi\u00e7\u00e3o de solu\u00e7\u00f5es que procurem torn\u00e1-la mais heterog\u00eanea.<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es que querem se manter relevantes e chamativas aos olhos do p\u00fablico. Mas o que exatamente \u00e9 diversidade? Por que ela \u00e9 importante para as empresas e como foment\u00e1-la? N\u00e3o se preocupe, preparamos um conte\u00fado especial! Veja [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":32449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[224],"tags":[11564,13748,13749],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.2 (Yoast SEO v22.2) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diversidade dentro da empresa: como praticar e aplicar? | Oitchau<\/title>\n<meta name=\"description\" content=\"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diversidade dentro da empresa: como praticar e aplicar?\" \/>\n<meta property=\"og:description\" content=\"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\" \/>\n<meta property=\"og:site_name\" content=\"Controle de Ponto &amp; Timesheets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/oitchaubr\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-06T22:56:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-29T14:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1982\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Aline Mesquita\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@oitchaubr\" \/>\n<meta name=\"twitter:site\" content=\"@oitchaubr\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aline Mesquita\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\"},\"author\":{\"name\":\"Aline Mesquita\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/person\/40ba65f8664531ffe1465f6cb9d82430\"},\"headline\":\"Diversidade dentro da empresa: como praticar e aplicar?\",\"datePublished\":\"2020-05-06T22:56:59+00:00\",\"dateModified\":\"2023-11-29T14:02:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\"},\"wordCount\":1580,\"publisher\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png\",\"keywords\":[\"diversidade\",\"pluralidade\",\"valoriza\u00e7\u00e3o\"],\"articleSection\":[\"Gest\u00e3o de Pessoas\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\",\"url\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\",\"name\":\"Diversidade dentro da empresa: como praticar e aplicar? | Oitchau\",\"isPartOf\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png\",\"datePublished\":\"2020-05-06T22:56:59+00:00\",\"dateModified\":\"2023-11-29T14:02:11+00:00\",\"description\":\"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage\",\"url\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png\",\"contentUrl\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png\",\"width\":1982,\"height\":800,\"caption\":\"diversidade dentro da empresa\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\/\/www.oitchau.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diversidade dentro da empresa: como praticar e aplicar?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#website\",\"url\":\"https:\/\/www.oitchau.com.br\/blog\/\",\"name\":\"Controle de Ponto & Timesheets\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.oitchau.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#organization\",\"name\":\"Oitchau\",\"url\":\"https:\/\/www.oitchau.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2024\/03\/a0e65c6f-design-sem-nome-20.png\",\"contentUrl\":\"https:\/\/storage.googleapis.com\/oitchaublog\/2024\/03\/a0e65c6f-design-sem-nome-20.png\",\"width\":696,\"height\":696,\"caption\":\"Oitchau\"},\"image\":{\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/oitchaubr\/\",\"https:\/\/twitter.com\/oitchaubr\",\"https:\/\/instagram.com\/oitchaubr\"],\"description\":\"A Oitchau \u00e9 uma solu\u00e7\u00e3o completa para gest\u00e3o de tempo dos colaboradores, atrav\u00e9s de suas solu\u00e7\u00f5es de controle de ponto & timesheets, ela permite que gestores, RH e DP possam gerenciar desde a jornada de trabalho de funcion\u00e1rios at\u00e9 a gest\u00e3o de tempo em projetos. Elevando o n\u00edvel estrat\u00e9gico do neg\u00f3cio de forma inteligente e assertiva, potencializando seus resultados e garantindo compliance com a Lei.\",\"email\":\"contato@oitchau.com.br\",\"telephone\":\"+551142102846\",\"foundingDate\":\"2016-01-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/person\/40ba65f8664531ffe1465f6cb9d82430\",\"name\":\"Aline Mesquita\",\"url\":\"https:\/\/www.oitchau.com.br\/blog\/author\/aline\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diversidade dentro da empresa: como praticar e aplicar? | Oitchau","description":"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/","og_locale":"pt_BR","og_type":"article","og_title":"Diversidade dentro da empresa: como praticar e aplicar?","og_description":"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!","og_url":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/","og_site_name":"Controle de Ponto &amp; Timesheets","article_publisher":"https:\/\/www.facebook.com\/oitchaubr\/","article_published_time":"2020-05-06T22:56:59+00:00","article_modified_time":"2023-11-29T14:02:11+00:00","og_image":[{"width":1982,"height":800,"url":"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png","type":"image\/png"}],"author":"Aline Mesquita","twitter_card":"summary_large_image","twitter_creator":"@oitchaubr","twitter_site":"@oitchaubr","twitter_misc":{"Written by":"Aline Mesquita","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#article","isPartOf":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/"},"author":{"name":"Aline Mesquita","@id":"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/person\/40ba65f8664531ffe1465f6cb9d82430"},"headline":"Diversidade dentro da empresa: como praticar e aplicar?","datePublished":"2020-05-06T22:56:59+00:00","dateModified":"2023-11-29T14:02:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/"},"wordCount":1580,"publisher":{"@id":"https:\/\/www.oitchau.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png","keywords":["diversidade","pluralidade","valoriza\u00e7\u00e3o"],"articleSection":["Gest\u00e3o de Pessoas"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/","url":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/","name":"Diversidade dentro da empresa: como praticar e aplicar? | Oitchau","isPartOf":{"@id":"https:\/\/www.oitchau.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage"},"image":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage"},"thumbnailUrl":"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png","datePublished":"2020-05-06T22:56:59+00:00","dateModified":"2023-11-29T14:02:11+00:00","description":"Hoje a diversidade dentro da empresa n\u00e3o se apresenta mais como uma op\u00e7\u00e3o \u00e0s empresas, mas como uma obriga\u00e7\u00e3o das institui\u00e7\u00f5es. Veja mais sobre isso!","breadcrumb":{"@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#primaryimage","url":"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png","contentUrl":"https:\/\/storage.googleapis.com\/oitchaublog\/2020\/05\/ed33b181-diversidade-dentro-da-empresa.png","width":1982,"height":800,"caption":"diversidade dentro da empresa"},{"@type":"BreadcrumbList","@id":"https:\/\/www.oitchau.com.br\/blog\/como-praticar-e-aplicar-a-diversidade-dentro-da-empresa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.oitchau.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Diversidade dentro da empresa: como praticar e aplicar?"}]},{"@type":"WebSite","@id":"https:\/\/www.oitchau.com.br\/blog\/#website","url":"https:\/\/www.oitchau.com.br\/blog\/","name":"Controle de Ponto & Timesheets","description":"","publisher":{"@id":"https:\/\/www.oitchau.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.oitchau.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.oitchau.com.br\/blog\/#organization","name":"Oitchau","url":"https:\/\/www.oitchau.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/storage.googleapis.com\/oitchaublog\/2024\/03\/a0e65c6f-design-sem-nome-20.png","contentUrl":"https:\/\/storage.googleapis.com\/oitchaublog\/2024\/03\/a0e65c6f-design-sem-nome-20.png","width":696,"height":696,"caption":"Oitchau"},"image":{"@id":"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/oitchaubr\/","https:\/\/twitter.com\/oitchaubr","https:\/\/instagram.com\/oitchaubr"],"description":"A Oitchau \u00e9 uma solu\u00e7\u00e3o completa para gest\u00e3o de tempo dos colaboradores, atrav\u00e9s de suas solu\u00e7\u00f5es de controle de ponto & timesheets, ela permite que gestores, RH e DP possam gerenciar desde a jornada de trabalho de funcion\u00e1rios at\u00e9 a gest\u00e3o de tempo em projetos. Elevando o n\u00edvel estrat\u00e9gico do neg\u00f3cio de forma inteligente e assertiva, potencializando seus resultados e garantindo compliance com a Lei.","email":"contato@oitchau.com.br","telephone":"+551142102846","foundingDate":"2016-01-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}},{"@type":"Person","@id":"https:\/\/www.oitchau.com.br\/blog\/#\/schema\/person\/40ba65f8664531ffe1465f6cb9d82430","name":"Aline Mesquita","url":"https:\/\/www.oitchau.com.br\/blog\/author\/aline\/"}]}},"_links":{"self":[{"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/posts\/9914"}],"collection":[{"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/comments?post=9914"}],"version-history":[{"count":2,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/posts\/9914\/revisions"}],"predecessor-version":[{"id":32451,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/posts\/9914\/revisions\/32451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/media\/32449"}],"wp:attachment":[{"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/media?parent=9914"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/categories?post=9914"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oitchau.com.br\/blog\/wp-json\/wp\/v2\/tags?post=9914"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}